{"id":9429,"count":1,"description":"","link":"https:\/\/press.azbuki.bg\/en\/tag\/cognitive-independence\/","name":"cognitive independence","slug":"cognitive-independence","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>cognitive independence Archives - \u0410\u0437-\u0431\u0443\u043a\u0438<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foreignlanguages.azbuki.bg\/en\/tag\/cognitive-independence\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"cognitive independence Archives - \u0410\u0437-\u0431\u0443\u043a\u0438\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foreignlanguages.azbuki.bg\/en\/tag\/cognitive-independence\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0410\u0437-\u0431\u0443\u043a\u0438\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/foreignlanguages.azbuki.bg\/en\/tag\/cognitive-independence\/\",\"url\":\"https:\/\/foreignlanguages.azbuki.bg\/en\/tag\/cognitive-independence\/\",\"name\":\"cognitive independence Archives - \u0410\u0437-\u0431\u0443\u043a\u0438\",\"isPartOf\":{\"@id\":\"https:\/\/mathinfo.azbuki.bg\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/foreignlanguages.azbuki.bg\/en\/tag\/cognitive-independence\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/foreignlanguages.azbuki.bg\/en\/tag\/cognitive-independence\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/azbuki.bg\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"cognitive independence\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mathinfo.azbuki.bg\/en\/#website\",\"url\":\"https:\/\/mathinfo.azbuki.bg\/en\/\",\"name\":\"\u0410\u0437-\u0431\u0443\u043a\u0438\",\"description\":\"\u041d\u0430\u0446\u0438\u043e\u043d\u0430\u043b\u043d\u043e \u0438\u0437\u0434\u0430\u0442\u0435\u043b\u0441\u0442\u0432\u043e \u0437\u0430 \u043e\u0431\u0440\u0430\u0437\u043e\u0432\u0430\u043d\u0438\u0435 \u0438 \u043d\u0430\u0443\u043a\u0430\",\"publisher\":{\"@id\":\"https:\/\/mathinfo.azbuki.bg\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mathinfo.azbuki.bg\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mathinfo.azbuki.bg\/en\/#organization\",\"name\":\"\u0410\u0437-\u0431\u0443\u043a\u0438\",\"url\":\"https:\/\/mathinfo.azbuki.bg\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mathinfo.azbuki.bg\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/azbuki.bg\/wp-content\/uploads\/2019\/04\/logo-azbuki-e1580374651845.png\",\"contentUrl\":\"https:\/\/azbuki.bg\/wp-content\/uploads\/2019\/04\/logo-azbuki-e1580374651845.png\",\"width\":250,\"height\":70,\"caption\":\"\u0410\u0437-\u0431\u0443\u043a\u0438\"},\"image\":{\"@id\":\"https:\/\/mathinfo.azbuki.bg\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Azbuki55\/\",\"https:\/\/www.instagram.com\/nion_azbuki\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"cognitive independence Archives - \u0410\u0437-\u0431\u0443\u043a\u0438","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foreignlanguages.azbuki.bg\/en\/tag\/cognitive-independence\/","og_locale":"en_US","og_type":"article","og_title":"cognitive independence Archives - \u0410\u0437-\u0431\u0443\u043a\u0438","og_url":"https:\/\/foreignlanguages.azbuki.bg\/en\/tag\/cognitive-independence\/","og_site_name":"\u0410\u0437-\u0431\u0443\u043a\u0438","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/foreignlanguages.azbuki.bg\/en\/tag\/cognitive-independence\/","url":"https:\/\/foreignlanguages.azbuki.bg\/en\/tag\/cognitive-independence\/","name":"cognitive independence Archives - \u0410\u0437-\u0431\u0443\u043a\u0438","isPartOf":{"@id":"https:\/\/mathinfo.azbuki.bg\/en\/#website"},"breadcrumb":{"@id":"https:\/\/foreignlanguages.azbuki.bg\/en\/tag\/cognitive-independence\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/foreignlanguages.azbuki.bg\/en\/tag\/cognitive-independence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/azbuki.bg\/"},{"@type":"ListItem","position":2,"name":"cognitive independence"}]},{"@type":"WebSite","@id":"https:\/\/mathinfo.azbuki.bg\/en\/#website","url":"https:\/\/mathinfo.azbuki.bg\/en\/","name":"\u0410\u0437-\u0431\u0443\u043a\u0438","description":"\u041d\u0430\u0446\u0438\u043e\u043d\u0430\u043b\u043d\u043e \u0438\u0437\u0434\u0430\u0442\u0435\u043b\u0441\u0442\u0432\u043e \u0437\u0430 \u043e\u0431\u0440\u0430\u0437\u043e\u0432\u0430\u043d\u0438\u0435 \u0438 \u043d\u0430\u0443\u043a\u0430","publisher":{"@id":"https:\/\/mathinfo.azbuki.bg\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mathinfo.azbuki.bg\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mathinfo.azbuki.bg\/en\/#organization","name":"\u0410\u0437-\u0431\u0443\u043a\u0438","url":"https:\/\/mathinfo.azbuki.bg\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mathinfo.azbuki.bg\/en\/#\/schema\/logo\/image\/","url":"https:\/\/azbuki.bg\/wp-content\/uploads\/2019\/04\/logo-azbuki-e1580374651845.png","contentUrl":"https:\/\/azbuki.bg\/wp-content\/uploads\/2019\/04\/logo-azbuki-e1580374651845.png","width":250,"height":70,"caption":"\u0410\u0437-\u0431\u0443\u043a\u0438"},"image":{"@id":"https:\/\/mathinfo.azbuki.bg\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Azbuki55\/","https:\/\/www.instagram.com\/nion_azbuki\/"]}]}},"_links":{"self":[{"href":"https:\/\/press.azbuki.bg\/en\/wp-json\/wp\/v2\/tags\/9429"}],"collection":[{"href":"https:\/\/press.azbuki.bg\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/press.azbuki.bg\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/press.azbuki.bg\/en\/wp-json\/wp\/v2\/posts?tags=9429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}